{"id":20261,"date":"2025-06-06T06:34:41","date_gmt":"2025-06-06T11:04:41","guid":{"rendered":"https:\/\/fcaunican.edu.py\/?p=20261"},"modified":"2025-06-06T06:34:41","modified_gmt":"2025-06-06T11:04:41","slug":"exitosa-realizacion-de-actividades-en-la-facultad-de-ciencias-agrarias-durante-la-i-semana-de-la-integracion-unioeste-unican-2025","status":"publish","type":"post","link":"https:\/\/fcaunican.edu.py\/index.php\/2025\/06\/06\/exitosa-realizacion-de-actividades-en-la-facultad-de-ciencias-agrarias-durante-la-i-semana-de-la-integracion-unioeste-unican-2025\/","title":{"rendered":"Exitosa realizaci\u00f3n de actividades en la Facultad de Ciencias Agrarias durante la I Semana de la Integraci\u00f3n UNIOESTE &#8211; UNICAN 2025"},"content":{"rendered":"<p>Los d\u00edas 3 y 5 de junio se llevaron a cabo con gran \u00e9xito las actividades programadas en la Facultad de Ciencias Agrarias, en el marco de la I Semana de la Integraci\u00f3n UNIOESTE &#8211; UNICAN 2025. El evento cont\u00f3 con la activa participaci\u00f3n de estudiantes, docentes y autoridades de la facultad, quienes se sumaron a las distintas propuestas acad\u00e9micas y de integraci\u00f3n.<!--more--><\/p>\n<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-20281\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/portada-2.jpg?resize=1024%2C500&#038;ssl=1\" alt=\"\" width=\"1024\" height=\"500\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/portada-2.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/portada-2.jpg?resize=300%2C146&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/portada-2.jpg?resize=768%2C375&amp;ssl=1 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>Durante las jornadas, se destac\u00f3 la presencia de reconocidos docentes de la UNIOESTE, quienes estuvieron a cargo de las disertaciones, aportando valiosos conocimientos y experiencias que enriquecieron el intercambio acad\u00e9mico entre las instituciones. La organizaci\u00f3n y el entusiasmo de los participantes consolidaron el evento como un espacio clave para fortalecer los lazos de cooperaci\u00f3n y el desarrollo acad\u00e9mico conjunto.<\/p>\n<div  id=\"jtg-20263\" class=\"modula modula-gallery modula-creative-gallery\" data-config=\"{&quot;height&quot;:800,&quot;tabletHeight&quot;:800,&quot;mobileHeight&quot;:800,&quot;desktopHeight&quot;:800,&quot;enableTwitter&quot;:false,&quot;enableWhatsapp&quot;:false,&quot;enableFacebook&quot;:false,&quot;enablePinterest&quot;:false,&quot;enableLinkedin&quot;:false,&quot;enableEmail&quot;:false,&quot;randomFactor&quot;:0.5,&quot;type&quot;:&quot;creative-gallery&quot;,&quot;columns&quot;:12,&quot;gutter&quot;:10,&quot;mobileGutter&quot;:10,&quot;tabletGutter&quot;:10,&quot;desktopGutter&quot;:10,&quot;enableResponsive&quot;:&quot;0&quot;,&quot;tabletColumns&quot;:2,&quot;mobileColumns&quot;:1,&quot;lazyLoad&quot;:1,&quot;lightboxOpts&quot;:{&quot;animated&quot;:true,&quot;Thumbs&quot;:{&quot;type&quot;:&quot;modern&quot;,&quot;showOnStart&quot;:false},&quot;Toolbar&quot;:{&quot;display&quot;:{&quot;right&quot;:[&quot;close&quot;]},&quot;enabled&quot;:true},&quot;Carousel&quot;:{&quot;Panzoom&quot;:{&quot;touch&quot;:true},&quot;infinite&quot;:false},&quot;keyboard&quot;:{&quot;Escape&quot;:&quot;close&quot;,&quot;Delete&quot;:&quot;close&quot;,&quot;Backspace&quot;:&quot;close&quot;,&quot;PageUp&quot;:false,&quot;PageDown&quot;:false,&quot;ArrowUp&quot;:false,&quot;ArrowDown&quot;:false,&quot;ArrowRight&quot;:false,&quot;ArrowLeft&quot;:false},&quot;touch&quot;:false,&quot;backdropClick&quot;:false,&quot;l10n&quot;:{&quot;CLOSE&quot;:&quot;Cerrar&quot;,&quot;NEXT&quot;:&quot;Siguiente&quot;,&quot;PREV&quot;:&quot;Anterior&quot;,&quot;Error&quot;:&quot;No se ha podido cargar el contenido solicitado. Por favor, int\\u00e9ntalo de nuevo m\\u00e1s tarde.&quot;,&quot;PLAY_START&quot;:&quot;Empezar la presentaci\\u00f3n&quot;,&quot;PLAY_STOP&quot;:&quot;Pausar la presentaci\\u00f3n&quot;,&quot;FULL_SCREEN&quot;:&quot;Pantalla completa&quot;,&quot;THUMBS&quot;:&quot;Miniaturas&quot;,&quot;DOWNLOAD&quot;:&quot;Descargar&quot;,&quot;SHARE&quot;:&quot;Compartir&quot;,&quot;ZOOM&quot;:&quot;Zoom&quot;,&quot;EMAIL&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;MODAL&quot;:&quot;Puedes cerrar este contenido emergente con la tecla ESC&quot;,&quot;ERROR&quot;:&quot;Algo ha ido mal, pro favor, prueba de nuevo m\\u00e1s tarde&quot;,&quot;IMAGE_ERROR&quot;:&quot;Imagen no encontrada&quot;,&quot;ELEMENT_NOT_FOUND&quot;:&quot;No se ha encontrado el elemento HTML&quot;,&quot;AJAX_NOT_FOUND&quot;:&quot;Error al cargar AJAX: No encontrado&quot;,&quot;AJAX_FORBIDDEN&quot;:&quot;Error al cargar AJAX: Prohibido&quot;,&quot;IFRAME_ERROR&quot;:&quot;Error al cargar la p\\u00e1gina&quot;,&quot;TOGGLE_ZOOM&quot;:&quot;Alternar nivel de ampliar\\\/acercar&quot;,&quot;TOGGLE_THUMBS&quot;:&quot;Alternar miniaturas&quot;,&quot;TOGGLE_SLIDESHOW&quot;:&quot;Alternar diapositiva&quot;,&quot;TOGGLE_FULLSCREEN&quot;:&quot;Cambiar al modo de pantalla completa&quot;},&quot;Images&quot;:{&quot;Panzoom&quot;:{&quot;maxScale&quot;:2}},&quot;mainClass&quot;:&quot;modula-fancybox-container modula-lightbox-jtg-20263&quot;,&quot;Html&quot;:{&quot;videoAutoplay&quot;:0,&quot;videoTpl&quot;:&quot;&lt;video class=\\&quot;fancybox__html5video\\&quot; controls muted playsinline controlsList controlsList=\\&quot;nodownload\\&quot; poster=\\&quot;{{poster}}\\&quot; src=\\&quot;{{src}}\\&quot; type=\\&quot;{{format}}\\&quot; &gt;  Sorry, your browser doesn&#039;t support embedded videos, &lt;a href=\\&quot;{{src}}\\&quot;&gt; download &lt;\\\/a&gt; and watch with your favorite video player! &lt;\\\/video&gt;&quot;}},&quot;inView&quot;:false,&quot;email_subject&quot;:&quot;Check out this awesome image !!&quot;,&quot;email_message&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;lightbox&quot;:&quot;fancybox&quot;}\">\n\n\t\n\t<div  class=\"modula-items\">\n\t\t<div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"20264\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-20263\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-20264 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-1-Large.jpg\" title=\"UNIOESTE (1) (Large)\" crop=\"\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-1-Large.jpg?fit=300%2C225&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-1-Large.jpg?fit=300%2C225&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-1-Large.jpg?w=1440&amp;ssl=1 1440w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-1-Large.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-1-Large.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-1-Large.jpg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"20265\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-20263\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-20265 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-1-Large.png\" title=\"UNIOESTE (1) (Large)\" crop=\"\" width=\"300\" height=\"130\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-1-Large.png?fit=300%2C130&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-1-Large.png?fit=300%2C130&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-1-Large.png?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-1-Large.png?resize=300%2C130&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-1-Large.png?resize=1024%2C442&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-1-Large.png?resize=768%2C332&amp;ssl=1 768w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-1-Large.png?resize=1536%2C663&amp;ssl=1 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"20266\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-20263\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-20266 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-2-Large.jpg\" title=\"UNIOESTE (2) (Large)\" crop=\"\" width=\"300\" height=\"135\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-2-Large.jpg?fit=300%2C135&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-2-Large.jpg?fit=300%2C135&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-2-Large.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-2-Large.jpg?resize=300%2C135&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-2-Large.jpg?resize=1024%2C461&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-2-Large.jpg?resize=768%2C346&amp;ssl=1 768w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-2-Large.jpg?resize=1536%2C691&amp;ssl=1 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"20267\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-20263\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-20267 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-2-Large.png\" title=\"UNIOESTE (2) (Large)\" crop=\"\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-2-Large.png?fit=300%2C225&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-2-Large.png?fit=300%2C225&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-2-Large.png?w=1440&amp;ssl=1 1440w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-2-Large.png?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-2-Large.png?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-2-Large.png?resize=768%2C576&amp;ssl=1 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"20268\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-20263\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-20268 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-3-Large.jpg\" title=\"UNIOESTE (3) (Large)\" crop=\"\" width=\"300\" height=\"135\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-3-Large.jpg?fit=300%2C135&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-3-Large.jpg?fit=300%2C135&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-3-Large.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-3-Large.jpg?resize=300%2C135&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-3-Large.jpg?resize=1024%2C461&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-3-Large.jpg?resize=768%2C346&amp;ssl=1 768w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-3-Large.jpg?resize=1536%2C691&amp;ssl=1 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"20269\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-20263\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-20269 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-3-Large.png\" title=\"UNIOESTE (3) (Large)\" crop=\"\" width=\"300\" height=\"151\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-3-Large.png?fit=300%2C151&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-3-Large.png?fit=300%2C151&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-3-Large.png?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-3-Large.png?resize=300%2C151&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-3-Large.png?resize=1024%2C516&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-3-Large.png?resize=768%2C387&amp;ssl=1 768w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-3-Large.png?resize=1536%2C774&amp;ssl=1 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"20270\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-20263\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-20270 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-4-Large.jpg\" title=\"UNIOESTE (4) (Large)\" crop=\"\" width=\"300\" height=\"135\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-4-Large.jpg?fit=300%2C135&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-4-Large.jpg?fit=300%2C135&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-4-Large.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-4-Large.jpg?resize=300%2C135&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-4-Large.jpg?resize=1024%2C461&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-4-Large.jpg?resize=768%2C346&amp;ssl=1 768w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-4-Large.jpg?resize=1536%2C691&amp;ssl=1 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"20271\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-20263\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-20271 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-4-Large.png\" title=\"UNIOESTE (4) (Large)\" crop=\"\" width=\"300\" height=\"149\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-4-Large.png?fit=300%2C149&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-4-Large.png?fit=300%2C149&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-4-Large.png?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-4-Large.png?resize=300%2C149&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-4-Large.png?resize=1024%2C509&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-4-Large.png?resize=768%2C382&amp;ssl=1 768w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-4-Large.png?resize=1536%2C764&amp;ssl=1 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"20272\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-20263\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-20272 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-5-Large.jpg\" title=\"UNIOESTE (5) (Large)\" crop=\"\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-5-Large.jpg?fit=300%2C225&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-5-Large.jpg?fit=300%2C225&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-5-Large.jpg?w=1440&amp;ssl=1 1440w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-5-Large.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-5-Large.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-5-Large.jpg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"20273\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-20263\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-20273 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-5-Large.png\" title=\"UNIOESTE (5) (Large)\" crop=\"\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-5-Large.png?fit=300%2C225&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-5-Large.png?fit=300%2C225&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-5-Large.png?w=1440&amp;ssl=1 1440w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-5-Large.png?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-5-Large.png?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-5-Large.png?resize=768%2C576&amp;ssl=1 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"20274\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-20263\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-20274 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-7-Large.png\" title=\"UNIOESTE (7) (Large)\" crop=\"\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-7-Large.png?fit=300%2C225&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-7-Large.png?fit=300%2C225&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-7-Large.png?w=1440&amp;ssl=1 1440w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-7-Large.png?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-7-Large.png?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-7-Large.png?resize=768%2C576&amp;ssl=1 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"20275\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-20263\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-20275 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-8-Large.png\" title=\"UNIOESTE (8) (Large)\" crop=\"\" width=\"300\" height=\"159\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-8-Large.png?fit=300%2C159&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-8-Large.png?fit=300%2C159&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-8-Large.png?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-8-Large.png?resize=300%2C159&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-8-Large.png?resize=1024%2C543&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-8-Large.png?resize=768%2C407&amp;ssl=1 768w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-8-Large.png?resize=1536%2C814&amp;ssl=1 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"20276\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-20263\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-20276 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-9-Large.png\" title=\"UNIOESTE (9) (Large)\" crop=\"\" width=\"300\" height=\"165\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-9-Large.png?fit=300%2C165&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-9-Large.png?fit=300%2C165&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-9-Large.png?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-9-Large.png?resize=300%2C165&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-9-Large.png?resize=1024%2C563&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-9-Large.png?resize=768%2C422&amp;ssl=1 768w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-9-Large.png?resize=1536%2C845&amp;ssl=1 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"20277\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-20263\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-20277 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-10-Large.png\" title=\"UNIOESTE (10) (Large)\" crop=\"\" width=\"300\" height=\"159\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-10-Large.png?fit=300%2C159&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-10-Large.png?fit=300%2C159&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-10-Large.png?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-10-Large.png?resize=300%2C159&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-10-Large.png?resize=1024%2C544&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-10-Large.png?resize=768%2C408&amp;ssl=1 768w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-10-Large.png?resize=1536%2C816&amp;ssl=1 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"20278\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-20263\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-20278 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-11-Large.png\" title=\"UNIOESTE (11) (Large)\" crop=\"\" width=\"300\" height=\"133\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-11-Large.png?fit=300%2C133&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-11-Large.png?fit=300%2C133&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-11-Large.png?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-11-Large.png?resize=300%2C133&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-11-Large.png?resize=1024%2C453&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-11-Large.png?resize=768%2C340&amp;ssl=1 768w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/UNIOESTE-11-Large.png?resize=1536%2C680&amp;ssl=1 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"20280\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-20263\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-20280 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/PORTADA-1.jpg\" title=\"PORTADA\" crop=\"\" width=\"300\" height=\"130\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/PORTADA-1.jpg?fit=300%2C130&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/PORTADA-1.jpg?fit=300%2C130&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/PORTADA-1.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/PORTADA-1.jpg?resize=300%2C130&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/PORTADA-1.jpg?resize=768%2C333&amp;ssl=1 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\t\t\n\t<\/div>\n\n\t\n\t\n\t<script type=\"application\/ld+json\">\n\t{\n\t\t\"@context\": \"https:\/\/schema.org\",\n\t\t\"@type\"   : \"ImageGallery\",\n\t\t\"id\"      : \"https:\/\/fcaunican.edu.py\/index.php\/2025\/06\/06\/exitosa-realizacion-de-actividades-en-la-facultad-de-ciencias-agrarias-durante-la-i-semana-de-la-integracion-unioeste-unican-2025\/#modula-gallery-20263\",\n\t\t\"url\"     : \"https:\/\/fcaunican.edu.py\/index.php\/2025\/06\/06\/exitosa-realizacion-de-actividades-en-la-facultad-de-ciencias-agrarias-durante-la-i-semana-de-la-integracion-unioeste-unican-2025\/\"\n\t}\n\n\t<\/script>\n\n\t\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Los d\u00edas 3 y 5 de junio se llevaron a cabo con gran \u00e9xito las actividades programadas en la Facultad de Ciencias Agrarias, en el marco de la I Semana de la Integraci\u00f3n UNIOESTE &#8211; UNICAN 2025. El evento cont\u00f3 con la activa participaci\u00f3n de estudiantes, docentes y autoridades de la facultad, quienes se sumaron [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4,3],"tags":[],"class_list":["post-20261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionalizacion","category-noticias"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/06\/portada-2.jpg?fit=1024%2C500&ssl=1","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/posts\/20261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/comments?post=20261"}],"version-history":[{"count":1,"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/posts\/20261\/revisions"}],"predecessor-version":[{"id":20282,"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/posts\/20261\/revisions\/20282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/media\/20281"}],"wp:attachment":[{"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/media?parent=20261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/categories?post=20261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/tags?post=20261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}