{"id":21076,"date":"2025-11-07T19:26:58","date_gmt":"2025-11-07T23:56:58","guid":{"rendered":"https:\/\/fcaunican.edu.py\/?p=21076"},"modified":"2025-11-07T19:26:58","modified_gmt":"2025-11-07T23:56:58","slug":"visita-tecnica-de-la-fca-a-laboratorios-de-la-unicentro","status":"publish","type":"post","link":"https:\/\/fcaunican.edu.py\/index.php\/2025\/11\/07\/visita-tecnica-de-la-fca-a-laboratorios-de-la-unicentro\/","title":{"rendered":"Visita t\u00e9cnica de la FCA a laboratorios de la UNICENTRO"},"content":{"rendered":"<p>(Guarapuava, 06\/11\/2025) \u2014 En el marco de las actividades acad\u00e9micas y de fortalecimiento de la formaci\u00f3n profesional, estudiantes de la Facultad de Ciencias Agrarias (FCA) realizaron una visita t\u00e9cnica a los laboratorios de la Universidade Estadual do Centro-Oeste (UNICENTRO), en el estado de Paran\u00e1, Brasil.<!--more--><\/p>\n<p>La delegaci\u00f3n estuvo encabezada por la directora Elida Peralta y acompa\u00f1ada por los docentes Gladys Monges y Robert Armoa. Durante la jornada, los estudiantes recorrieron distintos laboratorios especializados, entre ellos:<\/p>\n<ul>\n<li>N\u00facleo de Mecaniza\u00e7\u00e3o e Agricultura de Precis\u00e3o (NMAP), coordinado por el Prof. Leandro Rampim.<\/li>\n<li>N\u00facleo de Plantio Direto (NPD), a cargo del Prof. Marcelo Cruz Mendes.<\/li>\n<li>N\u00facleo de Produ\u00e7\u00e3o Animal (NUPRAN), bajo la coordinaci\u00f3n del Prof. Mikael Neumann.<\/li>\n<li>Laborat\u00f3rio de F\u00edsica, Manejo e Conserva\u00e7\u00e3o do Solo, dirigido por el Prof. Cristiano Pott.<\/li>\n<\/ul>\n<p>La actividad permiti\u00f3 a los estudiantes observar de cerca las pr\u00e1cticas e investigaciones aplicadas en el \u00e1mbito de la agricultura de precisi\u00f3n, la producci\u00f3n animal y la conservaci\u00f3n de suelos, fortaleciendo as\u00ed la vinculaci\u00f3n acad\u00e9mica y cient\u00edfica entre ambas instituciones.<\/p>\n<p>La Facultad de Ciencias Agrarias agradece a la UNICENTRO, a sus docentes e investigadores por la cordial recepci\u00f3n, apertura y disposici\u00f3n para compartir conocimientos que enriquecen la formaci\u00f3n profesional de nuestros estudiantes.<\/p>\n<div  id=\"jtg-21077\" class=\"modula modula-gallery modula-creative-gallery\" data-config=\"{&quot;height&quot;:800,&quot;tabletHeight&quot;:800,&quot;mobileHeight&quot;:800,&quot;desktopHeight&quot;:800,&quot;enableTwitter&quot;:false,&quot;enableWhatsapp&quot;:false,&quot;enableFacebook&quot;:false,&quot;enablePinterest&quot;:false,&quot;enableLinkedin&quot;:false,&quot;enableEmail&quot;:false,&quot;randomFactor&quot;:0.5,&quot;type&quot;:&quot;creative-gallery&quot;,&quot;columns&quot;:12,&quot;gutter&quot;:10,&quot;mobileGutter&quot;:10,&quot;tabletGutter&quot;:10,&quot;desktopGutter&quot;:10,&quot;enableResponsive&quot;:true,&quot;tabletColumns&quot;:2,&quot;mobileColumns&quot;:1,&quot;lazyLoad&quot;:1,&quot;lightboxOpts&quot;:{&quot;animated&quot;:true,&quot;Thumbs&quot;:{&quot;type&quot;:&quot;modern&quot;,&quot;showOnStart&quot;:false},&quot;Toolbar&quot;:{&quot;display&quot;:{&quot;right&quot;:[&quot;close&quot;]},&quot;enabled&quot;:true},&quot;Carousel&quot;:{&quot;Panzoom&quot;:{&quot;touch&quot;:true},&quot;infinite&quot;:false},&quot;keyboard&quot;:{&quot;Escape&quot;:&quot;close&quot;,&quot;Delete&quot;:&quot;close&quot;,&quot;Backspace&quot;:&quot;close&quot;,&quot;PageUp&quot;:false,&quot;PageDown&quot;:false,&quot;ArrowUp&quot;:false,&quot;ArrowDown&quot;:false,&quot;ArrowRight&quot;:false,&quot;ArrowLeft&quot;:false},&quot;touch&quot;:false,&quot;backdropClick&quot;:false,&quot;l10n&quot;:{&quot;CLOSE&quot;:&quot;Cerrar&quot;,&quot;NEXT&quot;:&quot;Siguiente&quot;,&quot;PREV&quot;:&quot;Anterior&quot;,&quot;Error&quot;:&quot;No se ha podido cargar el contenido solicitado. Por favor, int\\u00e9ntalo de nuevo m\\u00e1s tarde.&quot;,&quot;PLAY_START&quot;:&quot;Empezar la presentaci\\u00f3n&quot;,&quot;PLAY_STOP&quot;:&quot;Pausar la presentaci\\u00f3n&quot;,&quot;FULL_SCREEN&quot;:&quot;Pantalla completa&quot;,&quot;THUMBS&quot;:&quot;Miniaturas&quot;,&quot;DOWNLOAD&quot;:&quot;Descargar&quot;,&quot;SHARE&quot;:&quot;Compartir&quot;,&quot;ZOOM&quot;:&quot;Zoom&quot;,&quot;EMAIL&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;MODAL&quot;:&quot;Puedes cerrar este contenido emergente con la tecla ESC&quot;,&quot;ERROR&quot;:&quot;Algo ha ido mal, pro favor, prueba de nuevo m\\u00e1s tarde&quot;,&quot;IMAGE_ERROR&quot;:&quot;Imagen no encontrada&quot;,&quot;ELEMENT_NOT_FOUND&quot;:&quot;No se ha encontrado el elemento HTML&quot;,&quot;AJAX_NOT_FOUND&quot;:&quot;Error al cargar AJAX: No encontrado&quot;,&quot;AJAX_FORBIDDEN&quot;:&quot;Error al cargar AJAX: Prohibido&quot;,&quot;IFRAME_ERROR&quot;:&quot;Error al cargar la p\\u00e1gina&quot;,&quot;TOGGLE_ZOOM&quot;:&quot;Alternar nivel de ampliar\\\/acercar&quot;,&quot;TOGGLE_THUMBS&quot;:&quot;Alternar miniaturas&quot;,&quot;TOGGLE_SLIDESHOW&quot;:&quot;Alternar diapositiva&quot;,&quot;TOGGLE_FULLSCREEN&quot;:&quot;Cambiar al modo de pantalla completa&quot;},&quot;Images&quot;:{&quot;Panzoom&quot;:{&quot;maxScale&quot;:2}},&quot;mainClass&quot;:&quot;modula-fancybox-container modula-lightbox-jtg-21077&quot;,&quot;Html&quot;:{&quot;videoAutoplay&quot;:0,&quot;videoTpl&quot;:&quot;&lt;video class=\\&quot;fancybox__html5video\\&quot; controls muted playsinline controlsList controlsList=\\&quot;nodownload\\&quot; poster=\\&quot;{{poster}}\\&quot; src=\\&quot;{{src}}\\&quot; type=\\&quot;{{format}}\\&quot; &gt;  Sorry, your browser doesn&#039;t support embedded videos, &lt;a href=\\&quot;{{src}}\\&quot;&gt; download &lt;\\\/a&gt; and watch with your favorite video player! &lt;\\\/video&gt;&quot;}},&quot;inView&quot;:false,&quot;email_subject&quot;:&quot;\\u00a1\\u00a1Mira esta impresionante imagen!!&quot;,&quot;email_message&quot;:&quot;Este es el enlace a la imagen: %%image_link%% y este es el enlace a la galer\\u00eda: %%gallery_link%%&quot;,&quot;lightbox&quot;:&quot;fancybox&quot;}\">\n\n\t\n\t<div  class=\"modula-items\">\n\t\t<div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"21078\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-21077\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-21078 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-1.jpeg\" title=\"labo (1)\" crop=\"\" width=\"300\" height=\"140\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-1.jpeg?fit=300%2C140&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-1.jpeg?fit=300%2C140&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-1.jpeg?w=1440&amp;ssl=1 1440w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-1.jpeg?resize=300%2C140&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-1.jpeg?resize=1024%2C478&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-1.jpeg?resize=768%2C358&amp;ssl=1 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"21079\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-21077\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img fetchpriority=\"high\" decoding=\"async\" class=\"pic wp-image-21079 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-1.jpg\" title=\"labo (1)\" crop=\"\" width=\"225\" height=\"300\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-1.jpg?fit=225%2C300&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-1.jpg?fit=225%2C300&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-1.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-1.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-1.jpg?resize=769%2C1024&amp;ssl=1 769w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-1.jpg?resize=768%2C1023&amp;ssl=1 768w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"21080\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-21077\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-21080 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-2.jpg\" title=\"labo (2)\" crop=\"\" width=\"300\" height=\"116\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-2.jpg?fit=300%2C116&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-2.jpg?fit=300%2C116&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-2.jpg?w=1342&amp;ssl=1 1342w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-2.jpg?resize=300%2C116&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-2.jpg?resize=1024%2C397&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-2.jpg?resize=768%2C298&amp;ssl=1 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"21081\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-21077\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-21081 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-4.jpg\" title=\"labo (4)\" crop=\"\" width=\"300\" height=\"150\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-4.jpg?fit=300%2C150&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-4.jpg?fit=300%2C150&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-4.jpg?w=1398&amp;ssl=1 1398w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-4.jpg?resize=300%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-4.jpg?resize=1024%2C511&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-4.jpg?resize=768%2C383&amp;ssl=1 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"21082\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-21077\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-21082 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-5.jpg\" title=\"labo (5)\" crop=\"\" width=\"225\" height=\"300\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-5-rotated.jpg?fit=225%2C300&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-5-rotated.jpg?fit=225%2C300&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-5-rotated.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-5-rotated.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-5-rotated.jpg?resize=768%2C1024&amp;ssl=1 768w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"21083\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-21077\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-21083 lazyload\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-6.jpg\" title=\"labo (6)\" crop=\"\" width=\"300\" height=\"135\" src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-6.jpg?fit=300%2C135&amp;ssl=1\" data-src=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-6.jpg?fit=300%2C135&amp;ssl=1\" data-caption=\"\" data-source=\"modula\" srcset=\"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-6.jpg?w=1341&amp;ssl=1 1341w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-6.jpg?resize=300%2C135&amp;ssl=1 300w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-6.jpg?resize=1024%2C461&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-6.jpg?resize=768%2C346&amp;ssl=1 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\t\t\n\t<\/div>\n\n\t\n\t\n\t<script type=\"application\/ld+json\">\n\t{\n\t\t\"@context\": \"https:\/\/schema.org\",\n\t\t\"@type\"   : \"ImageGallery\",\n\t\t\"id\"      : \"https:\/\/fcaunican.edu.py\/index.php\/2025\/11\/07\/visita-tecnica-de-la-fca-a-laboratorios-de-la-unicentro\/#modula-gallery-21077\",\n\t\t\"url\"     : \"https:\/\/fcaunican.edu.py\/index.php\/2025\/11\/07\/visita-tecnica-de-la-fca-a-laboratorios-de-la-unicentro\/\"\n\t}\n\n\t<\/script>\n\n\t\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>(Guarapuava, 06\/11\/2025) \u2014 En el marco de las actividades acad\u00e9micas y de fortalecimiento de la formaci\u00f3n profesional, estudiantes de la Facultad de Ciencias Agrarias (FCA) realizaron una visita t\u00e9cnica a los laboratorios de la Universidade Estadual do Centro-Oeste (UNICENTRO), en el estado de Paran\u00e1, Brasil.<\/p>\n","protected":false},"author":1,"featured_media":21078,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4,3],"tags":[],"class_list":["post-21076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionalizacion","category-noticias"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/fcaunican.edu.py\/wp-content\/uploads\/2025\/11\/labo-1.jpeg?fit=1440%2C672&ssl=1","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/posts\/21076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/comments?post=21076"}],"version-history":[{"count":2,"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/posts\/21076\/revisions"}],"predecessor-version":[{"id":21085,"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/posts\/21076\/revisions\/21085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/media\/21078"}],"wp:attachment":[{"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/media?parent=21076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/categories?post=21076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fcaunican.edu.py\/index.php\/wp-json\/wp\/v2\/tags?post=21076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}